{"id":3280,"date":"2017-03-03T22:53:54","date_gmt":"2017-03-04T03:53:54","guid":{"rendered":"http:\/\/www.sintradeua.org\/home\/?p=3280"},"modified":"2017-03-03T22:53:54","modified_gmt":"2017-03-04T03:53:54","slug":"que-son-derechos-adquiridos-expectativas-legitimas-y-simples-expectativas-en-materia-pensional","status":"publish","type":"post","link":"https:\/\/sintradeua.org\/co\/que-son-derechos-adquiridos-expectativas-legitimas-y-simples-expectativas-en-materia-pensional\/","title":{"rendered":"Qu\u00e9 son derechos adquiridos, expectativas leg\u00edtimas y simples expectativas en materia pensional?"},"content":{"rendered":"<div id=\"cc-m-10471257249\" class=\"j-module n j-text \">\n<p class=\"font_8\" style=\"padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Arial, '\uff4d\uff53 \uff50\u30b4\u30b7\u30c3\u30af', 'ms pgothic', \ub3cb\uc6c0, dotum, helvetica, sans-serif; color: #616060; text-align: justify; background: transparent;\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/image.jimcdn.com\/app\/cms\/image\/transf\/none\/path\/s2ac8cf77c7fcbc05\/image\/i2f963bb3951ea7af\/version\/1450811266\/image.jpg?w=640&#038;ssl=1\" alt=\"Por: Sandra Milena Vanegas Barrag\u00e1n\" \/><\/p>\n<p class=\"font_8\" style=\"padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Arial, '\uff4d\uff53 \uff50\u30b4\u30b7\u30c3\u30af', 'ms pgothic', \ub3cb\uc6c0, dotum, helvetica, sans-serif; color: #616060; text-align: justify; background: transparent;\"><span style=\"color: #344a5f;\">La diferencia fundamental entre los derechos adquiridos, las expectativas leg\u00edtimas y las meras expectativas consiste, en que los primeros son los \u00fanicos que han ingresado plenamente al patrimonio de una persona, por encontrarse satisfechos los requisitos que la ley vigente -para ese momento- se\u00f1ale, lo que hace plenamente exigible su reconocimiento. Los derechos adquiridos, por mandato constitucional, en ning\u00fan caso pueden ser objeto de medidas regresivas, es decir, no pueden ser desconocidos por derechos posteriores, ya que fueron consolidados previo a la expedici\u00f3n de la nueva ley.<\/span><\/p>\n<\/div>\n<p><!--more--><\/p>\n<div id=\"cc-m-10471260449\" class=\"j-module n j-text \">\n<p class=\"font_8\" style=\"padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Arial, '\uff4d\uff53 \uff50\u30b4\u30b7\u30c3\u30af', 'ms pgothic', \ub3cb\uc6c0, dotum, helvetica, sans-serif; color: #616060; text-align: justify; background: transparent;\"><span style=\"color: #344a5f;\"><span style=\"background-color: transparent;\">A su turno, las meras expectativas, o, simples expectativas, son producto de la diferencia que existe entre aquellas personas que apenas inician en la vida laboral al momento de expedirse una nueva ley y aquellas que se encuentran en avanzado proceso. Las meras expectativas cobijan a todas aquellas personas cuyas posibilidades de pensionarse resultan lejanas y por tanto no gozan de protecci\u00f3n constitucional,<\/span><span style=\"background-color: transparent;\">\u00a0<\/span><span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-weight: bold; background: transparent;\">en tanto, los requisitos para acceder a una prestaci\u00f3n pueden ser reguladas por el legislador a su discreci\u00f3n.<\/span><\/span><\/p>\n<p class=\"font_8\" style=\"padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Arial, '\uff4d\uff53 \uff50\u30b4\u30b7\u30c3\u30af', 'ms pgothic', \ub3cb\uc6c0, dotum, helvetica, sans-serif; color: #616060; text-align: justify; background: transparent;\"><span style=\"color: #344a5f;\">\u00a0<\/span><span style=\"color: #344a5f;\">Ahora bien, entre \u00e9stas dos situaciones jur\u00eddicas la Corte Constitucional mediante Sentencia T-789 de 2002 estableci\u00f3 una categor\u00eda intermedia denominada\u00a0<span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-weight: bold; background: transparent;\">expectativas leg\u00edtimas<\/span>, siendo \u00e9stas aquellas que tienen ciertas personas, de alcanzar un derecho pensional bajo determinado r\u00e9gimen y que se caracterizan por carecer de alguno de los requisitos que la ley exige para hacer efectivo su reconocimiento, se genera cuando, al momento de introducirse un cambio normativo, la persona muestra un avance significativo en la adquisici\u00f3n de la prestaci\u00f3n V.gr. Cuando una persona ha cotizado al sistema por los menos la mitad de su vida laboral. Su protecci\u00f3n se despliega mediante la creaci\u00f3n de reg\u00edmenes de transici\u00f3n, cuya finalidad es la protecci\u00f3n de derechos en v\u00eda de adquisici\u00f3n del cual deriva el principio de no regresividad a las expectativas pensionales cercanas del trabajador.<\/span><\/p>\n<p class=\"font_8\" style=\"padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Arial, '\uff4d\uff53 \uff50\u30b4\u30b7\u30c3\u30af', 'ms pgothic', \ub3cb\uc6c0, dotum, helvetica, sans-serif; color: #616060; text-align: justify; background: transparent;\"><span style=\"color: #344a5f;\">\u00a0<\/span><span style=\"color: #344a5f;\">La Sentencia T-789 de 2002 indic\u00f3:\u00a0<span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-style: italic; background: transparent;\">\u00absi bien es cierto, trat\u00e1ndose de meras expectativas no aplica la prohibici\u00f3n de regresividad, ello no significa que est\u00e9n desprovistas de toda protecci\u00f3n, pues cualquier transito normativo no solo debe consultar los principios de razonabilidad y proporcionalidad, sino que, adem\u00e1s, en funci\u00f3n del principio de confianza leg\u00edtima, se debe proteger la creencia cierta del administrado de que la regulaci\u00f3n que lo ampara en un derecho se seguir\u00e1 manteniendo vigente en el ordenamiento jur\u00eddico. Por tal raz\u00f3n, la Corte ha se\u00f1alado que cu\u00e1nto m\u00e1s cerca est\u00e1 una persona de acceder al goce efectivo de un derecho, mayor es la legitimidad de su expectativa en este sentido.\u00bb<\/span><\/span><\/p>\n<p class=\"font_8\" style=\"padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Arial, '\uff4d\uff53 \uff50\u30b4\u30b7\u30c3\u30af', 'ms pgothic', \ub3cb\uc6c0, dotum, helvetica, sans-serif; color: #616060; text-align: justify; background: transparent;\"><span style=\"color: #344a5f;\">\u00a0<\/span><span style=\"color: #344a5f;\">Aterrizando lo anterior podr\u00edamos decir que el derecho a una pensi\u00f3n de vejez es considerado un derecho adquirido, cuando la persona ha cumplido los requisitos de\u00a0<span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-weight: bold; background: transparent;\">edad<\/span>\u00a0y\u00a0<span style=\"margin: 0px; padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-weight: bold; background: transparent;\">n\u00famero de cotizaciones<\/span>; cuando falte alguno de ellos, pero sea factible que se supere en tiempo razonable, estamos frente una expectativa leg\u00edtima; cuando faltan los dos requisitos y adem\u00e1s resulta improbable que en alg\u00fan momento se configure la adquisici\u00f3n del derecho, estamos hablando de una mera expectativa.<\/span><\/p>\n<p class=\"font_8\" style=\"padding: 0px; border: 0px; outline: 0px; vertical-align: baseline; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Arial, '\uff4d\uff53 \uff50\u30b4\u30b7\u30c3\u30af', 'ms pgothic', \ub3cb\uc6c0, dotum, helvetica, sans-serif; color: #616060; text-align: justify; background: transparent;\"><span style=\"color: #344a5f;\">\u00a0<\/span><span style=\"color: #344a5f;\">Pese a lo anterior, el novedoso pero ilusorio concepto de expectativas leg\u00edtimas carece de alguna forma real de protecci\u00f3n constitucional, m\u00e1s a\u00fan con la expedici\u00f3n del Acto Legislativo 01 de 2005, del cual nos ocuparemos en una pr\u00f3xima nota.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La diferencia fundamental entre los derechos adquiridos, las expectativas leg\u00edtimas y las meras expectativas consiste, en que los primeros son los \u00fanicos que han ingresado plenamente al patrimonio de una persona, por encontrarse satisfechos los requisitos que la ley vigente -para ese momento- se\u00f1ale, lo que hace plenamente exigible su reconocimiento. Los derechos adquiridos, por&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-3280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/sintradeua.org\/co\/wp-content\/uploads\/2017\/03\/88.jpg?fit=265%2C265&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paSj5R-QU","_links":{"self":[{"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/posts\/3280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/comments?post=3280"}],"version-history":[{"count":2,"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/posts\/3280\/revisions"}],"predecessor-version":[{"id":3283,"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/posts\/3280\/revisions\/3283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/media\/3281"}],"wp:attachment":[{"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/media?parent=3280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/categories?post=3280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sintradeua.org\/co\/wp-json\/wp\/v2\/tags?post=3280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}